{"id":9,"date":"2023-04-18T14:29:01","date_gmt":"2023-04-18T14:29:01","guid":{"rendered":"http:\/\/www.buy4lessdeals.com\/index.php\/my-account\/"},"modified":"2023-04-18T14:29:01","modified_gmt":"2023-04-18T14:29:01","slug":"my-account","status":"publish","type":"page","link":"http:\/\/www.buy4lessdeals.com\/index.php\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.buy4lessdeals.com\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}